{"id":700,"date":"2017-10-09T11:14:00","date_gmt":"2017-10-09T09:14:00","guid":{"rendered":"http:\/\/prod.bymycar.fr\/webzine\/?p=700"},"modified":"2019-11-12T15:40:16","modified_gmt":"2019-11-12T14:40:16","slug":"ford-express-service-revision-met-gomme","status":"publish","type":"post","link":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/","title":{"rendered":"Ford Express Service, la r\u00e9vision qui met la gomme"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":935,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[131,2,4],"tags":[],"class_list":["post-700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ford","category-lactu-des-marques","category-offres-et-bons-plans"],"acf":{"introduction":"<p>Entretien en 1 heure, intervention de deux techniciens et services associ\u00e9s, Ford Express Service est le nouveau service de r\u00e9vision lanc\u00e9 par Ford en 2016.<\/p>\n","strates":[{"type_strate":"texte-simple","ancre":"","contenu":"<h2>Ford Express Service : votre r\u00e9vision Ford en seulement 1h !<\/h2>\n<p>Depuis septembre 2016, <strong>Ford innove gr\u00e2ce \u00e0 un service efficace et utile : le Ford Express Service<\/strong>. Permettant de profiter d\u2019une r\u00e9vision de qualit\u00e9 en seulement 1 heure, ce service d\u2019entretien est con\u00e7u pour r\u00e9pondre aux besoins des professionnels. <strong>Tour d\u2019horizon de cette nouvelle r\u00e9vision Ford<\/strong>.<\/p>\n","titre":"","image":false,"image_libre":false,"image_800x500":false,"legende":"","zoom":false,"texte":"","articles":false,"categorie_droite":false,"images":false,"elements_comparatif":false,"texte_1":"","texte_2":"","image_1":false,"image_1_563x400":false,"image_1_332x332":false,"image_2":false,"image_2_333x240":false,"image_2_563x400":false,"image_3":false,"image_3_333x240":false,"image_3_332x450":false,"image_4":false,"image_4_332x332":false,"image_4_563x400":false,"code_embed":"","legende_video":"","photo":false,"photo_100x100":false,"nom":"","fonction":"","elements_timeline":false,"entetes_colonnes":false,"entetes_lignes":false,"lignes":false,"introduction":"","formulaire":false,"question":"","reponse":"","libelle_bouton_lien":"","url_lien":"","questions":false,"conclusions":false,"pays":false,"region":false,"marque":false,"marqueConcessions":false,"modele":false,"ptvente":false,"typeV":false,"collection":false,"nombre_maximum_elements":10,"lien_fin_carousel":"","texte_lien_fin_carousel":"","trier_par":false},{"type_strate":"image","ancre":"","contenu":"","titre":"","image":false,"image_libre":false,"image_800x500":false,"legende":"","zoom":false,"texte":"","articles":false,"categorie_droite":false,"images":[{"image":{"ID":933,"id":933,"title":"Ford logo","filename":"logo-ford-e1499246395498.jpg","filesize":0,"url":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/logo-ford-e1499246395498.jpg","link":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/ford-logo\/","alt":"Ford logo","author":"1","description":"Ford logo","caption":"","name":"ford-logo","status":"inherit","uploaded_to":700,"date":"2017-07-05 09:17:01","modified":"2017-08-02 13:20:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bymycar.fr\/webzine\/wp-includes\/images\/media\/default.png","width":3869,"height":1959,"sizes":{"thumbnail":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/logo-ford-e1499246395498-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/logo-ford-e1499246395498-300x152.jpg","medium-width":300,"medium-height":152,"medium_large":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/logo-ford-e1499246395498-768x389.jpg","medium_large-width":768,"medium_large-height":389,"large":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/logo-ford-e1499246395498-1024x518.jpg","large-width":1024,"large-height":518,"1536x1536":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/logo-ford-e1499246395498.jpg","1536x1536-width":1536,"1536x1536-height":778,"2048x2048":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/logo-ford-e1499246395498.jpg","2048x2048-width":2048,"2048x2048-height":1037}},"image_1600x700":false,"image_920x500":false,"legende":""}],"elements_comparatif":false,"texte_1":"","texte_2":"","image_1":false,"image_1_563x400":false,"image_1_332x332":false,"image_2":false,"image_2_333x240":false,"image_2_563x400":false,"image_3":false,"image_3_333x240":false,"image_3_332x450":false,"image_4":false,"image_4_332x332":false,"image_4_563x400":false,"code_embed":"","legende_video":"","photo":false,"photo_100x100":false,"nom":"","fonction":"","elements_timeline":false,"entetes_colonnes":false,"entetes_lignes":false,"lignes":false,"introduction":"","formulaire":false,"question":"","reponse":"","libelle_bouton_lien":"","url_lien":"","questions":false,"conclusions":false,"pays":false,"region":false,"marque":false,"marqueConcessions":false,"modele":false,"ptvente":false,"typeV":false,"collection":false,"nombre_maximum_elements":10,"lien_fin_carousel":"","texte_lien_fin_carousel":"","trier_par":false},{"type_strate":"texte-simple","ancre":"","contenu":"<h2>Une r\u00e9vision Ford rapide et adapt\u00e9e aux besoins des professionnels<\/h2>\n<p><strong>Ford Express Service, c&rsquo;est le tout nouveau service d&rsquo;entretien et de r\u00e9vision Ford<\/strong>. Gr\u00e2ce \u00e0 deux techniciens exp\u00e9riment\u00e9s, les professionnels peuvent profiter du meilleur de l&rsquo;expertise Ford pour leur v\u00e9hicule. Pour r\u00e9pondre aux imp\u00e9ratifs des pros, le constructeur va encore plus loin : <strong>il r\u00e9alise ce service d&rsquo;entretien en seulement une heure<\/strong>. L\u2019objectif est d\u2019ailleurs de r\u00e9duire le temps d\u2019immobilisation du v\u00e9hicule au maximum. L\u2019id\u00e9al pour faire r\u00e9viser sa voiture entre deux r\u00e9unions ou le temps de sa pause d\u00e9jeuner.<\/p>\n","titre":"","image":false,"image_libre":false,"image_800x500":false,"legende":"","zoom":false,"texte":"","articles":false,"categorie_droite":false,"images":false,"elements_comparatif":false,"texte_1":"","texte_2":"","image_1":false,"image_1_563x400":false,"image_1_332x332":false,"image_2":false,"image_2_333x240":false,"image_2_563x400":false,"image_3":false,"image_3_333x240":false,"image_3_332x450":false,"image_4":false,"image_4_332x332":false,"image_4_563x400":false,"code_embed":"","legende_video":"","photo":false,"photo_100x100":false,"nom":"","fonction":"","elements_timeline":false,"entetes_colonnes":false,"entetes_lignes":false,"lignes":false,"introduction":"","formulaire":false,"question":"","reponse":"","libelle_bouton_lien":"","url_lien":"","questions":false,"conclusions":false,"pays":false,"region":false,"marque":false,"marqueConcessions":false,"modele":false,"ptvente":false,"typeV":false,"collection":false,"nombre_maximum_elements":10,"lien_fin_carousel":"","texte_lien_fin_carousel":"","trier_par":false},{"type_strate":"texte-simple","ancre":"","contenu":"<h2>Avec Ford Express Service, profitez de nombreux services associ\u00e9s<\/h2>\n<p><strong>Avec Ford Express Service, les professionnels peuvent profiter de diff\u00e9rents services associ\u00e9s le temps de la r\u00e9vision<\/strong>. En plus de pouvoir regarder les m\u00e9caniciens r\u00e9aliser le contr\u00f4le de leur v\u00e9hicule, ils ont la possibilit\u00e9 de rester connect\u00e9 gr\u00e2ce \u00e0 une <strong>connexion WiFi gratuite<\/strong>. Durant la r\u00e9vision Ford, les clients ont \u00e9galement deux autres possibilit\u00e9s : <strong>essayer n\u2019importe quelle voiture du constructeur et configurer le mod\u00e8le de leur choix<\/strong>. Autant dire qu\u2019il n\u2019y a pas le temps de s\u2019ennuyer !<\/p>\n","titre":"","image":false,"image_libre":false,"image_800x500":false,"legende":"","zoom":false,"texte":"","articles":false,"categorie_droite":false,"images":false,"elements_comparatif":false,"texte_1":"","texte_2":"","image_1":false,"image_1_563x400":false,"image_1_332x332":false,"image_2":false,"image_2_333x240":false,"image_2_563x400":false,"image_3":false,"image_3_333x240":false,"image_3_332x450":false,"image_4":false,"image_4_332x332":false,"image_4_563x400":false,"code_embed":"","legende_video":"","photo":false,"photo_100x100":false,"nom":"","fonction":"","elements_timeline":false,"entetes_colonnes":false,"entetes_lignes":false,"lignes":false,"introduction":"","formulaire":false,"question":"","reponse":"","libelle_bouton_lien":"","url_lien":"","questions":false,"conclusions":false,"pays":false,"region":false,"marque":false,"marqueConcessions":false,"modele":false,"ptvente":false,"typeV":false,"collection":false,"nombre_maximum_elements":10,"lien_fin_carousel":"","texte_lien_fin_carousel":"","trier_par":false},{"type_strate":"image","ancre":"","contenu":"","titre":"","image":false,"image_libre":false,"image_800x500":false,"legende":"","zoom":false,"texte":"","articles":false,"categorie_droite":false,"images":[{"image":{"ID":934,"id":934,"title":"m\u00e9canicien garagiste qui parle avec un client","filename":"mecanicien-client-voiture-e1499250563249.jpg","filesize":0,"url":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-client-voiture-e1499250563249.jpg","link":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/auto-mechanic-talking-with-car-owner\/","alt":"m\u00e9canicien garagiste qui parle avec un client","author":"1","description":"m\u00e9canicien garagiste qui parle avec un client","caption":"","name":"auto-mechanic-talking-with-car-owner","status":"inherit","uploaded_to":700,"date":"2017-07-05 09:18:07","modified":"2017-08-02 13:21:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bymycar.fr\/webzine\/wp-includes\/images\/media\/default.png","width":2000,"height":1100,"sizes":{"thumbnail":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-client-voiture-e1499250563249-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-client-voiture-e1499250563249-300x165.jpg","medium-width":300,"medium-height":165,"medium_large":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-client-voiture-e1499250563249-768x422.jpg","medium_large-width":768,"medium_large-height":422,"large":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-client-voiture-e1499250563249-1024x563.jpg","large-width":1024,"large-height":563,"1536x1536":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-client-voiture-e1499250563249.jpg","1536x1536-width":1536,"1536x1536-height":845,"2048x2048":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-client-voiture-e1499250563249.jpg","2048x2048-width":2000,"2048x2048-height":1100}},"image_1600x700":false,"image_920x500":false,"legende":""}],"elements_comparatif":false,"texte_1":"","texte_2":"","image_1":false,"image_1_563x400":false,"image_1_332x332":false,"image_2":false,"image_2_333x240":false,"image_2_563x400":false,"image_3":false,"image_3_333x240":false,"image_3_332x450":false,"image_4":false,"image_4_332x332":false,"image_4_563x400":false,"code_embed":"","legende_video":"","photo":false,"photo_100x100":false,"nom":"","fonction":"","elements_timeline":false,"entetes_colonnes":false,"entetes_lignes":false,"lignes":false,"introduction":"","formulaire":false,"question":"","reponse":"","libelle_bouton_lien":"","url_lien":"","questions":false,"conclusions":false,"pays":false,"region":false,"marque":false,"marqueConcessions":false,"modele":false,"ptvente":false,"typeV":false,"collection":false,"nombre_maximum_elements":10,"lien_fin_carousel":"","texte_lien_fin_carousel":"","trier_par":false},{"type_strate":"texte-simple","ancre":"","contenu":"<h2>La r\u00e9vision Ford taill\u00e9e sur mesure pour les pros<\/h2>\n<p>Cette nouvelle formule de r\u00e9vision Ford offre deux avantages principaux : <strong>une r\u00e9duction du temps d\u2019immobilisation de la voiture et la possibilit\u00e9 de s\u2019occuper durant l\u2019entretien<\/strong>. Raison pour laquelle, avec Ford Express Service, Ford risque de marquer des points aupr\u00e8s de cette client\u00e8le exigeante et press\u00e9e que sont les professionnels.<\/p>\n","titre":"","image":false,"image_libre":false,"image_800x500":false,"legende":"","zoom":false,"texte":"","articles":false,"categorie_droite":false,"images":false,"elements_comparatif":false,"texte_1":"","texte_2":"","image_1":false,"image_1_563x400":false,"image_1_332x332":false,"image_2":false,"image_2_333x240":false,"image_2_563x400":false,"image_3":false,"image_3_333x240":false,"image_3_332x450":false,"image_4":false,"image_4_332x332":false,"image_4_563x400":false,"code_embed":"","legende_video":"","photo":false,"photo_100x100":false,"nom":"","fonction":"","elements_timeline":false,"entetes_colonnes":false,"entetes_lignes":false,"lignes":false,"introduction":"","formulaire":false,"question":"","reponse":"","libelle_bouton_lien":"","url_lien":"","questions":false,"conclusions":false,"pays":false,"region":false,"marque":false,"marqueConcessions":false,"modele":false,"ptvente":false,"typeV":false,"collection":false,"nombre_maximum_elements":10,"lien_fin_carousel":"","texte_lien_fin_carousel":"","trier_par":false},{"type_strate":"texte-simple","ancre":"","contenu":"<p>Envie de b\u00e9n\u00e9ficier de ce service ? N\u2019h\u00e9sitez pas \u00e0 <a href=\"https:\/\/www.bymycar.fr\/prise-de-rendez-vous-atelier?service=128\">prendre rendez-vous en atelier pour profiter du Ford Express Service<\/a> au sein d\u2019une concession ByMyCar.<\/p>\n","titre":"","image":false,"image_libre":false,"image_800x500":false,"legende":"","zoom":false,"texte":"","articles":false,"categorie_droite":false,"images":false,"elements_comparatif":false,"texte_1":"","texte_2":"","image_1":false,"image_1_563x400":false,"image_1_332x332":false,"image_2":false,"image_2_333x240":false,"image_2_563x400":false,"image_3":false,"image_3_333x240":false,"image_3_332x450":false,"image_4":false,"image_4_332x332":false,"image_4_563x400":false,"code_embed":"","legende_video":"","photo":false,"photo_100x100":false,"nom":"","fonction":"","elements_timeline":false,"entetes_colonnes":false,"entetes_lignes":false,"lignes":false,"introduction":"","formulaire":false,"question":"","reponse":"","libelle_bouton_lien":"","url_lien":"","questions":false,"conclusions":false,"pays":false,"region":false,"marque":false,"marqueConcessions":false,"modele":false,"ptvente":false,"typeV":false,"collection":false,"nombre_maximum_elements":10,"lien_fin_carousel":"","texte_lien_fin_carousel":"","trier_par":false}],"is_old_post":false,"image":{"ID":935,"id":935,"title":"m\u00e9canicien garagiste qui pose sous une voiture","filename":"mecanicien-revison-voiture-e1500284580941.jpg","filesize":0,"url":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg","link":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/portrait-of-a-mechanic-replacing-wheel\/","alt":"m\u00e9canicien garagiste qui pose sous une voiture","author":"1","description":"m\u00e9canicien garagiste qui pose sous une voiture","caption":"Portrait of a mechanic replacing a wheel","name":"portrait-of-a-mechanic-replacing-wheel","status":"inherit","uploaded_to":700,"date":"2017-07-05 09:18:23","modified":"2018-03-07 08:49:22","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bymycar.fr\/webzine\/wp-includes\/images\/media\/default.png","width":1565,"height":1335,"sizes":{"thumbnail":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941-300x256.jpg","medium-width":300,"medium-height":256,"medium_large":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941-768x655.jpg","medium_large-width":768,"medium_large-height":655,"large":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941-1024x874.jpg","large-width":1024,"large-height":874,"1536x1536":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg","1536x1536-width":1536,"1536x1536-height":1310,"2048x2048":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg","2048x2048-width":1565,"2048x2048-height":1335}},"page_content":{"block_content":[{"acf_fc_layout":"text-simple","--nav":{"-withNav":false,"-ancre":""},"--group":{"-text":"<h2>Ford Express Service : votre r\u00e9vision Ford en seulement 1h !<\/h2>\n<p>Depuis septembre 2016, <strong>Ford innove gr\u00e2ce \u00e0 un service efficace et utile : le Ford Express Service<\/strong>. Permettant de profiter d\u2019une r\u00e9vision de qualit\u00e9 en seulement 1 heure, ce service d\u2019entretien est con\u00e7u pour r\u00e9pondre aux besoins des professionnels. <strong>Tour d\u2019horizon de cette nouvelle r\u00e9vision Ford<\/strong>.<\/p>\n"}},{"acf_fc_layout":"images-slider","--nav":{"-withNav":false,"-ancre":""},"--group":{"-listibg":[{"--image":false,"--legend":""}]}},{"acf_fc_layout":"text-simple","--nav":{"-withNav":false,"-ancre":""},"--group":{"-text":"<h2>Une r\u00e9vision Ford rapide et adapt\u00e9e aux besoins des professionnels<\/h2>\n<p><strong>Ford Express Service, c&rsquo;est le tout nouveau service d&rsquo;entretien et de r\u00e9vision Ford<\/strong>. Gr\u00e2ce \u00e0 deux techniciens exp\u00e9riment\u00e9s, les professionnels peuvent profiter du meilleur de l&rsquo;expertise Ford pour leur v\u00e9hicule. Pour r\u00e9pondre aux imp\u00e9ratifs des pros, le constructeur va encore plus loin : <strong>il r\u00e9alise ce service d&rsquo;entretien en seulement une heure<\/strong>. L\u2019objectif est d\u2019ailleurs de r\u00e9duire le temps d\u2019immobilisation du v\u00e9hicule au maximum. L\u2019id\u00e9al pour faire r\u00e9viser sa voiture entre deux r\u00e9unions ou le temps de sa pause d\u00e9jeuner.<\/p>\n"}},{"acf_fc_layout":"text-simple","--nav":{"-withNav":false,"-ancre":""},"--group":{"-text":"<h2>Avec Ford Express Service, profitez de nombreux services associ\u00e9s<\/h2>\n<p><strong>Avec Ford Express Service, les professionnels peuvent profiter de diff\u00e9rents services associ\u00e9s le temps de la r\u00e9vision<\/strong>. En plus de pouvoir regarder les m\u00e9caniciens r\u00e9aliser le contr\u00f4le de leur v\u00e9hicule, ils ont la possibilit\u00e9 de rester connect\u00e9 gr\u00e2ce \u00e0 une <strong>connexion WiFi gratuite<\/strong>. Durant la r\u00e9vision Ford, les clients ont \u00e9galement deux autres possibilit\u00e9s : <strong>essayer n\u2019importe quelle voiture du constructeur et configurer le mod\u00e8le de leur choix<\/strong>. Autant dire qu\u2019il n\u2019y a pas le temps de s\u2019ennuyer !<\/p>\n"}},{"acf_fc_layout":"images-slider","--nav":{"-withNav":false,"-ancre":""},"--group":{"-listibg":[{"--image":false,"--legend":""}]}},{"acf_fc_layout":"text-simple","--nav":{"-withNav":false,"-ancre":""},"--group":{"-text":"<h2>La r\u00e9vision Ford taill\u00e9e sur mesure pour les pros<\/h2>\n<p>Cette nouvelle formule de r\u00e9vision Ford offre deux avantages principaux : <strong>une r\u00e9duction du temps d\u2019immobilisation de la voiture et la possibilit\u00e9 de s\u2019occuper durant l\u2019entretien<\/strong>. Raison pour laquelle, avec Ford Express Service, Ford risque de marquer des points aupr\u00e8s de cette client\u00e8le exigeante et press\u00e9e que sont les professionnels.<\/p>\n"}},{"acf_fc_layout":"text-simple","--nav":{"-withNav":false,"-ancre":""},"--group":{"-text":"<p>Envie de b\u00e9n\u00e9ficier de ce service ? N\u2019h\u00e9sitez pas \u00e0 <a href=\"https:\/\/www.bymycar.fr\/prise-de-rendez-vous-atelier?service=128\">prendre rendez-vous en atelier pour profiter du Ford Express Service<\/a> au sein d\u2019une concession ByMyCar.<\/p>\n"}}]},"add-carousel-to-footer":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v26.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ford Express Service, la r\u00e9vision qui met la gomme<\/title>\n<meta name=\"description\" content=\"Entretien en 1 heure, intervention de deux techniciens et services associ\u00e9s, Ford Express Service est le nouveau service de r\u00e9vision lanc\u00e9 par Ford en 2016.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ford Express Service, la r\u00e9vision qui met la gomme\" \/>\n<meta property=\"og:description\" content=\"Entretien en 1 heure, intervention de deux techniciens et services associ\u00e9s, Ford Express Service est le nouveau service de r\u00e9vision lanc\u00e9 par Ford en 2016.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/\" \/>\n<meta property=\"og:site_name\" content=\"Webzine auto BYmyCAR\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-09T09:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-12T14:40:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1565\" \/>\n\t<meta property=\"og:image:height\" content=\"1335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"William M.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"William M.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/\"},\"author\":{\"name\":\"William M.\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/person\/605ad02925224befd4475d11e8378cdc\"},\"headline\":\"Ford Express Service, la r\u00e9vision qui met la gomme\",\"datePublished\":\"2017-10-09T09:14:00+00:00\",\"dateModified\":\"2019-11-12T14:40:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg\",\"articleSection\":[\"FORD\",\"L'actu des marques\",\"Offres et bons plans\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/\",\"url\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/\",\"name\":\"Ford Express Service, la r\u00e9vision qui met la gomme\",\"isPartOf\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg\",\"datePublished\":\"2017-10-09T09:14:00+00:00\",\"dateModified\":\"2019-11-12T14:40:16+00:00\",\"description\":\"Entretien en 1 heure, intervention de deux techniciens et services associ\u00e9s, Ford Express Service est le nouveau service de r\u00e9vision lanc\u00e9 par Ford en 2016.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#primaryimage\",\"url\":\"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg\",\"contentUrl\":\"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg\",\"width\":1565,\"height\":1335,\"caption\":\"Portrait of a mechanic replacing a wheel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.bymycar.fr\/webzine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ford Express Service, la r\u00e9vision qui met la gomme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#website\",\"url\":\"https:\/\/www.bymycar.fr\/webzine\/\",\"name\":\"Webzine auto BYmyCAR\",\"description\":\"La magazine auto de BYmyCAR\",\"publisher\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bymycar.fr\/webzine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#organization\",\"name\":\"BYmyCAR\",\"url\":\"https:\/\/www.bymycar.fr\/webzine\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.bymycar.eu\/fr-webzine\/wp-content\/uploads\/medias\/2017\/08\/logo_DEALER_00000406_001.png\",\"contentUrl\":\"https:\/\/cdn.bymycar.eu\/fr-webzine\/wp-content\/uploads\/medias\/2017\/08\/logo_DEALER_00000406_001.png\",\"width\":2132,\"height\":720,\"caption\":\"BYmyCAR\"},\"image\":{\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/person\/605ad02925224befd4475d11e8378cdc\",\"name\":\"William M.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a53bfa67adaa4c04e552efd6b3d29aa707d64c3b462f4596e91af5e74cda882?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a53bfa67adaa4c04e552efd6b3d29aa707d64c3b462f4596e91af5e74cda882?s=96&d=mm&r=g\",\"caption\":\"William M.\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ford Express Service, la r\u00e9vision qui met la gomme","description":"Entretien en 1 heure, intervention de deux techniciens et services associ\u00e9s, Ford Express Service est le nouveau service de r\u00e9vision lanc\u00e9 par Ford en 2016.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/","og_locale":"fr_FR","og_type":"article","og_title":"Ford Express Service, la r\u00e9vision qui met la gomme","og_description":"Entretien en 1 heure, intervention de deux techniciens et services associ\u00e9s, Ford Express Service est le nouveau service de r\u00e9vision lanc\u00e9 par Ford en 2016.","og_url":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/","og_site_name":"Webzine auto BYmyCAR","article_published_time":"2017-10-09T09:14:00+00:00","article_modified_time":"2019-11-12T14:40:16+00:00","og_image":[{"width":1565,"height":1335,"url":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg","type":"image\/jpeg"}],"author":"William M.","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"William M."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#article","isPartOf":{"@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/"},"author":{"name":"William M.","@id":"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/person\/605ad02925224befd4475d11e8378cdc"},"headline":"Ford Express Service, la r\u00e9vision qui met la gomme","datePublished":"2017-10-09T09:14:00+00:00","dateModified":"2019-11-12T14:40:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/"},"wordCount":10,"publisher":{"@id":"https:\/\/www.bymycar.fr\/webzine\/#organization"},"image":{"@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg","articleSection":["FORD","L'actu des marques","Offres et bons plans"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/","url":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/","name":"Ford Express Service, la r\u00e9vision qui met la gomme","isPartOf":{"@id":"https:\/\/www.bymycar.fr\/webzine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#primaryimage"},"image":{"@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg","datePublished":"2017-10-09T09:14:00+00:00","dateModified":"2019-11-12T14:40:16+00:00","description":"Entretien en 1 heure, intervention de deux techniciens et services associ\u00e9s, Ford Express Service est le nouveau service de r\u00e9vision lanc\u00e9 par Ford en 2016.","breadcrumb":{"@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#primaryimage","url":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg","contentUrl":"https:\/\/www.bymycar.fr\/webzine\/wp-content\/uploads\/2017\/07\/mecanicien-revison-voiture-e1500284580941.jpg","width":1565,"height":1335,"caption":"Portrait of a mechanic replacing a wheel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bymycar.fr\/webzine\/ford-express-service-revision-met-gomme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bymycar.fr\/webzine\/"},{"@type":"ListItem","position":2,"name":"Ford Express Service, la r\u00e9vision qui met la gomme"}]},{"@type":"WebSite","@id":"https:\/\/www.bymycar.fr\/webzine\/#website","url":"https:\/\/www.bymycar.fr\/webzine\/","name":"Webzine auto BYmyCAR","description":"La magazine auto de BYmyCAR","publisher":{"@id":"https:\/\/www.bymycar.fr\/webzine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bymycar.fr\/webzine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bymycar.fr\/webzine\/#organization","name":"BYmyCAR","url":"https:\/\/www.bymycar.fr\/webzine\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.bymycar.eu\/fr-webzine\/wp-content\/uploads\/medias\/2017\/08\/logo_DEALER_00000406_001.png","contentUrl":"https:\/\/cdn.bymycar.eu\/fr-webzine\/wp-content\/uploads\/medias\/2017\/08\/logo_DEALER_00000406_001.png","width":2132,"height":720,"caption":"BYmyCAR"},"image":{"@id":"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/person\/605ad02925224befd4475d11e8378cdc","name":"William M.","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bymycar.fr\/webzine\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a53bfa67adaa4c04e552efd6b3d29aa707d64c3b462f4596e91af5e74cda882?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a53bfa67adaa4c04e552efd6b3d29aa707d64c3b462f4596e91af5e74cda882?s=96&d=mm&r=g","caption":"William M."}}]}},"_links":{"self":[{"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/posts\/700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/comments?post=700"}],"version-history":[{"count":10,"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/posts\/700\/revisions"}],"predecessor-version":[{"id":9711,"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/posts\/700\/revisions\/9711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/media\/935"}],"wp:attachment":[{"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/media?parent=700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/categories?post=700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bymycar.fr\/webzine\/wp-json\/wp\/v2\/tags?post=700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}